{"id":8452,"date":"2023-07-18T00:05:33","date_gmt":"2023-07-17T22:05:33","guid":{"rendered":"https:\/\/bk1.myalb.it\/hoteliaccarino.it\/it\/?page_id=8452"},"modified":"2026-06-05T00:33:21","modified_gmt":"2026-06-04T22:33:21","slug":"chambres-dhotes-classic-sant-agata-sui-due-golfi","status":"publish","type":"page","link":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/","title":{"rendered":"Chambre Classic"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8452\" class=\"elementor elementor-8452\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4fb756 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"d4fb756\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7cea58\" data-id=\"e7cea58\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eed849 elementor-widget elementor-widget-heading\" data-id=\"4eed849\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Classic <br>Confort et d\u00e9tente<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46485ef elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"46485ef\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bbe024\" data-id=\"1bbe024\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73994e4 elementor-widget elementor-widget-shortcode\" data-id=\"73994e4\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script>\r\n\tvar $jj = jQuery.noConflict();\r\n\t$jj(function()\r\n\t{\r\n\t\t\t\t$jj.datepicker.regional['it'] = {\r\n\t\t\t\t\tcloseText: 'Chiudi', \/\/ set a close button text\r\n\t\t\t    currentText: 'Oggi', \/\/ set today text\r\n\t\t\t    monthNames: ['Gennaio','Febbraio','Marzo','Aprile','Maggio','Giugno',   'Luglio','Agosto','Settembre','Ottobre','Novembre','Dicembre'], \/\/ set month names\r\n\t\t\t    monthNamesShort: ['Gen','Feb','Mar','Apr','Mag','Giu','Lug','Ago','Set','Ott','Nov','Dic'], \/\/ set short month names\r\n\t\t\t    dayNames: ['Domenica','Luned&#236','Marted&#236','Mercoled&#236','Gioved&#236','Venerd&#236','Sabato'], \/\/ set days names\r\n\t\t\t    dayNamesShort: ['Dom','Lun','Mar','Mer','Gio','Ven','Sab'], \/\/ set short day names\r\n\t\t\t    dayNamesMin: ['Do','Lu','Ma','Me','Gio','Ve','Sa'], \/\/ set more short days names\r\n\t\t\t    dateFormat: 'dd\/mm\/yy' \/\/ set format date\r\n\t\t\t\t};\r\n\t\t$jj.datepicker.setDefaults($jj.datepicker.regional['it']);\r\n\t\t$jj( \"#dataIn\" ).datepicker({\r\n\t\t\t\tdateFormat: \"dd-mm-yy\",\/\/per la lingua  inglese: \"yy-mm-dd\"\r\n\t\t\t\tminDate: new Date(2026, 07 - 1, 15),\r\n\t\t\t\tonClose: function() { setPartenza() }\r\n\t\t\t});\r\n\t\t$jj( \"#dataOut\" ).datepicker({\r\n\t\t\t  regional: \"IT\",\r\n\t\t\t\tdateFormat: \"dd-mm-yy\",\/\/per la lingua  inglese: \"yy-mm-dd\"\r\n\t\t\t\tminDate: new Date(2026, 07 - 1, 15)\r\n\t\t\t});\r\n\t});\r\n\r\n\r\n\tfunction Obbligatorio()\r\n\t{\r\n\t\tcontrolla('frmRicercaDisponibilitaPortale');\r\n\t};\r\n\/\/javascript:controlla(\".'\"frmRicercaDisponibilitaPortale\"'.\");\r\n<\/script>\r\n<script type=\"text\/javascript\">\r\n\tfunction setPartenza()\r\n\t{\r\n\t\tDate.prototype.addDays = function(intDays) {this.setDate(this.getDate() + intDays);}\r\n\t\tdataArrivo = document.getElementById(\"dataIn\").value;\r\n\t\tdA = dataArrivo.split(\"-\");\r\n\r\n\t\tif('it'=='it')\r\n\t\t\tdata = new Date(dA[1]+\"\/\"+dA[0]+\"\/\"+dA[2]);\r\n\t\telse\r\n\t\t\tdata = new Date(dA[1]+\"\/\"+dA[2]+\"\/\"+dA[0]);\r\n\r\n\t\tdata.addDays(1);\r\n\r\n\t\tif(data.getDate()<10) {\tdd = \"0\"+data.getDate(); } else\t{ dd = data.getDate(); }\r\n\t\tif(data.getMonth()<9) { mm = \"0\"+(data.getMonth()+1); } else { mm = data.getMonth()+1; }\r\n\r\n\t\tif('it'=='it')\r\n\t\t\tdocument.getElementById(\"dataOut\").value = dd+\"-\"+mm+\"-\"+data.getFullYear();\r\n\t\telse\r\n\t\t\tdocument.getElementById(\"dataOut\").value = data.getFullYear()+\"-\"+mm+\"-\"+dd;\r\n\t}\r\n\r\n\r\n\tfunction controlla(id)\r\n\t{\r\n\t\tvar form = document.getElementById(id);\r\n\t\tdataArr  = form.dataIn.value;\r\n\t\tdataPart = form.dataOut.value;\r\n\r\n\t\tdA = dataArr.split(\"-\");\r\n\t\tdP = dataPart.split(\"-\");\r\n\r\n\t\tif(dA[0].length < 2) { dA[0] = \"0\"+dA[0]; }\r\n\t\tif(dA[1].length < 2) { dA[1] = \"0\"+dA[1]; }\r\n\r\n\t\tdataArrivo   = dA[2]+dA[1]+dA[0];\r\n\t\tdataPartenza = dP[2]+dP[1]+dP[0];\r\n\r\n\t\tif(dataPartenza <= dataArrivo) {\r\n\t\t\talert(\"Attenzione! La data partenza deve essere superiore della data arrivo.\");\r\n\t\t  \treturn false;\r\n\t\t}\r\n\t\telse\r\n\t\t{\r\n\t\t\tform.submit();\r\n\t\t}\r\n\t}\r\n<\/script>\r\n\t\t<div class=\"elementor-shortcode\"><HTML> <meta name='viewport' content='width=device-width, initial-scale=1, minimum-scale=1, maximum-scale=1'><link href='https:\/\/www.hoteliaccarino.eu\/fr\/booking\/css\/book_form_date.css' rel='stylesheet' type='text\/css' media='all' \/>\r\n\t\t\t\t <link href='https:\/\/www.hoteliaccarino.eu\/fr\/booking\/css\/jquery-ui-1.10.4.custom.css' rel='stylesheet'>\r\n\t\t\t\t <script src='https:\/\/www.hoteliaccarino.eu\/fr\/booking\/js\/jquery-ui-1.10.4.custom.js'><\/script><div class='square-box'>\r\n    \t\t\t<div class='square-content'>\r\n\t\t\t\t\t\t<form target='_black' name='frmRicercaDisponibilitaPortale' id='frmRicercaDisponibilitaPortale' method='post' action='https:\/\/w1.myalb.it\/booking\/v5\/index.php' onSubmit='return controlla(this)'>\t\t\t<div id='booking-in'>\r\n\t \t\t\t\t\t\t\t<input type='hidden' name='hcid' value='67rd5f0f1m617585750b45c65678beg1'>\r\n\t\t\t          <input type='hidden' name='view' value='step1'>\r\n\t\t\t \t\t\t\t\t<input type='hidden' name='lang' value='en'>\r\n\t\t\t \t\t\t\t\t<span id='arrivo_trigger'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>Arrivo<\/label>--> <input type='text' name='dataIn' id='dataIn' size='10' readonly placeholder='arriv\u00e9e' value='16-07-2026'>&nbsp;<!--<img id='img-cal-a' src='images\/showcal.gif' align='absbottom'>-->\r\n\t\t\t\t\t\t\t\t<\/span>\r\n \t\t\t\t\t\t\t\t<span id='partenza_trigger'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>Partenza<\/label>--> <input type='text' name='dataOut' id='dataOut' size='10' placeholder='d\u00e9part' readonly value='17-07-2026'>&nbsp;<!--<img id='img-cal-p' src='images\/showcal.gif' align='absbottom'>-->\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/div>\t\t\t<div id='blocco-destro'>\r\n\t\t\t\t\t\t\t\t<span id='persone'>\r\n\t\t\t\t\t\t\t\t\t<!--<label>People<\/label>--><input type='number' id='adulti' name='adulti' placeholder='Gens' size='3' maxlength='2' max= '4' min='1' \/>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t<span id='book-search'>\r\n\t\t\t\t\t\t\t\t\t<a id='cerca' onclick='javascript:Obbligatorio();'>recherche<\/a>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/div>\t\t<\/form>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><\/HTML><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38f9b1c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38f9b1c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9c780f6\" data-id=\"9c780f6\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ab667b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2ab667b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">lit double \/ deux lits s\u00e9par\u00e9s<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-487196c\" data-id=\"487196c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ee8a8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"81ee8a8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Salle de bain priv\u00e9e<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d3a5ef0\" data-id=\"d3a5ef0\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95c414d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"95c414d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wifi gratuit<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-450ffe4\" data-id=\"450ffe4\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb05aec elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cb05aec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Climatisation<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a72b40c\" data-id=\"a72b40c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcb2ace elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fcb2ace\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:600,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 personnes<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed28c14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed28c14\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88e4398\" data-id=\"88e4398\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e49edcf elementor-widget elementor-widget-image\" data-id=\"e49edcf\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" src=\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2026\/06\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_camera_classic_4.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9b9fa03\" data-id=\"9b9fa03\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ef7921 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4ef7921\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Confort et d\u00e9tente<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93fe4ae elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"93fe4ae\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avec les merveilles <br> de Sant'Agata<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-559a454 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"559a454\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Delicata fodera in organza blu ricamata trasparente con pieghe elasticizzate in misto acetato di lusso. Dettaglio in pelle spalla contrasto colore contorno splendida silhouette di lavoro peplo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6711da3 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6711da3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>chambre double avec fen\u00eatre, A\/C, Wi-Fi, TV satellite, coffre-fort, minibar, t\u00e9l\u00e9phone, bain ou douche, articles de toilette, s\u00e8che-cheveux, peignoir, pantoufles, possibilit\u00e9 d&#8217;un troisi\u00e8me et quatri\u00e8me lit.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7019572 elementor-align-left elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"7019572\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/w1.myalb.it\/booking\/v5\/index.php?hcid=67rd5f0f1m617585750b45c65678beg1&#038;view=step1&#038;lang=en\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9server cette chambre<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1af6789 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1af6789\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2473230\" data-id=\"2473230\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4627ee9 elementor-widget elementor-widget-hoteller-slider-parallax\" data-id=\"4627ee9\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-slider-parallax.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"slider_parallax_wrapper\" data-autoplay=\"0\" data-pagination=\"0\" data-navigation=\"1\">\n\t<div class=\"slider_parallax_inner\">\n\t\t<div class=\"slider_parallax_slides\">\n\t\t\t\t\t\t<div class=\"slide is-active \">\n\t\t          \t<div class=\"slide-content\">\n\t\t            \t<div class=\"caption\">\n\t\t\t\t\t\t\t<div class=\"title\"><h2><\/h2><\/div>\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t                \t\t\t\t              \t\t<\/div> \n\t\t\t                \t\t            \t<\/div>\n\t\t          \t<\/div>\n\t\t\t\t  \t<div class=\"image-container\"> \n\t\t            \t<img decoding=\"async\" src=\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2026\/06\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_camera_classic_3.jpg\" alt=\"\" class=\"image\" \/>\n\t\t          \t<\/div>\n\t\t        <\/div>\n\t\t\t\t<\/div>\n\t\t\t    \t    <div class=\"arrows\">\n\t        <div class=\"arrow prev\">\n\t          <span class=\"svg svg-arrow-left\">\n\t            <svg version=\"1.1\" id=\"svg4-Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"14px\" height=\"26px\" viewBox=\"0 0 14 26\" enable-background=\"new 0 0 14 26\" xml:space=\"preserve\"> <path d=\"M13,26c-0.256,0-0.512-0.098-0.707-0.293l-12-12c-0.391-0.391-0.391-1.023,0-1.414l12-12c0.391-0.391,1.023-0.391,1.414,0s0.391,1.023,0,1.414L2.414,13l11.293,11.293c0.391,0.391,0.391,1.023,0,1.414C13.512,25.902,13.256,26,13,26z\"\/> <\/svg>\n\t            <span class=\"alt sr-only\"><\/span>\n\t          <\/span>\n\t        <\/div>\n\t        <div class=\"arrow next\">\n\t          <span class=\"svg svg-arrow-right\">\n\t            <svg version=\"1.1\" id=\"svg5-Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"14px\" height=\"26px\" viewBox=\"0 0 14 26\" enable-background=\"new 0 0 14 26\" xml:space=\"preserve\"> <path d=\"M1,0c0.256,0,0.512,0.098,0.707,0.293l12,12c0.391,0.391,0.391,1.023,0,1.414l-12,12c-0.391,0.391-1.023,0.391-1.414,0s-0.391-1.023,0-1.414L11.586,13L0.293,1.707c-0.391-0.391-0.391-1.023,0-1.414C0.488,0.098,0.744,0,1,0z\"\/> <\/svg>\n\t            <span class=\"alt sr-only\"><\/span>\n\t          <\/span>\n\t        <\/div>\n\t    <\/div>\n\t    \t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e24128d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e24128d\" data-element_type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3609f9c\" data-id=\"3609f9c\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4cb799 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c4cb799\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques de la chambre<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3732f9c elementor-widget elementor-widget-spacer\" data-id=\"3732f9c\" data-element_type=\"widget\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3799fbf elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3799fbf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Choix entre (lit double) ou (deux lits s\u00e9par\u00e9s).<br \/>Salle de bains avec baignoire ou douche, s\u00e8che-cheveux, miroir grossissant, s\u00e9lection d&#8217;articles de toilette, peignoirs, pantoufles, serviettes de piscine\/de mer.<br \/>T\u00e9l\u00e9vision \u00e0 \u00e9cran plat avec cha\u00eenes satellite.<br \/>Armoire avec coffre-fort.<br \/>Climatisation individuelle de juin \u00e0 septembre.<br \/>Chauffage individuel.<br \/>T\u00e9l\u00e9phone direct.<br \/>Minibar payant.<br \/>Bureau de travail.<br \/>Acc\u00e8s gratuit au wifi et \u00e0 Internet.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2019042 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2019042\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400,&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2026\/06\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_camera_classic_2.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ecb69d7\" data-id=\"ecb69d7\" data-element_type=\"column\" data-settings=\"{&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e47e9e8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e47e9e8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;hoteller_image_is_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" src=\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2026\/06\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_camera_classic_5.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Classic Confort et d\u00e9tente lit double \/ deux lits s\u00e9par\u00e9s Salle de bain priv\u00e9e Wifi gratuit Climatisation 2 personnes Confort et d\u00e9tente Avec les merveilles de Sant&#8217;Agata Delicata fodera in organza blu ricamata trasparente con pieghe elasticizzate in misto acetato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7841,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8452","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chambre Classic Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino<\/title>\n<meta name=\"description\" content=\"Chambre Classic Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chambre Classic Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino\" \/>\n<meta property=\"og:description\" content=\"Chambre Classic Hotel Sant&#039;Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Iaccarino\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T22:33:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1499\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/\",\"url\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/\",\"name\":\"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino\",\"isPartOf\":{\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg\",\"datePublished\":\"2023-07-17T22:05:33+00:00\",\"dateModified\":\"2026-06-04T22:33:21+00:00\",\"description\":\"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage\",\"url\":\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg\",\"contentUrl\":\"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg\",\"width\":1499,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hoteliaccarino.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chambre Classic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hoteliaccarino.eu\/fr\/#website\",\"url\":\"https:\/\/www.hoteliaccarino.eu\/fr\/\",\"name\":\"Hotel Iaccarino\",\"description\":\"Hotel a Sorrento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hoteliaccarino.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","description":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/","og_locale":"it_IT","og_type":"article","og_title":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","og_description":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.","og_url":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/","og_site_name":"Hotel Iaccarino","article_modified_time":"2026-06-04T22:33:21+00:00","og_image":[{"width":1499,"height":1000,"url":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/","url":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/","name":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino","isPartOf":{"@id":"https:\/\/www.hoteliaccarino.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage"},"image":{"@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg","datePublished":"2023-07-17T22:05:33+00:00","dateModified":"2026-06-04T22:33:21+00:00","description":"Chambre Classic Hotel Sant'Agata Sui Due Golfi | Hotel Iaccarino. Les chambres Classic sont dot\u00e9es de nombreux \u00e9quipements.","breadcrumb":{"@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#primaryimage","url":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg","contentUrl":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-content\/uploads\/2023\/02\/Hotel_Iaccarino_a_sant_agata_sui_due_golfi_hotel_foto_slide_camere_pagina_home_1.jpg","width":1499,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.hoteliaccarino.eu\/fr\/chambres-dhotes-classic-sant-agata-sui-due-golfi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hoteliaccarino.it\/it\/"},{"@type":"ListItem","position":2,"name":"Chambre Classic"}]},{"@type":"WebSite","@id":"https:\/\/www.hoteliaccarino.eu\/fr\/#website","url":"https:\/\/www.hoteliaccarino.eu\/fr\/","name":"Hotel Iaccarino","description":"Hotel a Sorrento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hoteliaccarino.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/pages\/8452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/comments?post=8452"}],"version-history":[{"count":14,"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/pages\/8452\/revisions"}],"predecessor-version":[{"id":10195,"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/pages\/8452\/revisions\/10195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/media\/7841"}],"wp:attachment":[{"href":"https:\/\/www.hoteliaccarino.eu\/fr\/wp-json\/wp\/v2\/media?parent=8452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}